{"id":121716,"date":"2021-01-12T20:22:50","date_gmt":"2021-01-13T02:22:50","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=121716"},"modified":"2021-01-12T20:22:50","modified_gmt":"2021-01-13T02:22:50","slug":"las-defensivas-dan-la-cara-en-la-postemporada-de-la-nfl","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/01\/12\/las-defensivas-dan-la-cara-en-la-postemporada-de-la-nfl\/","title":{"rendered":"Fallan ofensivas de Seattle, Tennessee y Chicago en NFL"},"content":{"rendered":"<p>Agencias\/ Ciudad de M\u00e9xico.- El recuerdo que perdura de las ofensivas de Seattle, Tennessee y Chicago este fin de semana han sido d\u00f3ciles.<\/p>\n<p>Incluso en una liga que impuso un nuevo r\u00e9cord de puntos, con m\u00e1s touchdowns que nunca, el trabajo de las defensa es un lujo invaluable en la postemporada. S\u00f3lo hay que preguntarles a los quarterbacks que fueron las v\u00edctimas, incluyendo al ganador del Super Bowl Russell Wilson, de los Seahawks.<\/p>\n<p>Preg\u00fantenle a Derrick Henry, el running back All-Pro de las 2.000 yardas con los Titans y cuya producci\u00f3n en la derrota del domingo ante Baltimore podr\u00eda medirse en pulgadas.<\/p>\n<p>Y a cualquiera en el ataque de los Bears, que lucieron m\u00e1s como osos de peluche que osos grizzly \u2014 gracias a la dominante defensiva de Nueva Orle\u00e1ns.<\/p>\n<p>\u201cNuestra defensa jug\u00f3 de manera sobresaliente\u201d, dijo el entrenador en jefe de Sean Payton tras la victoria de los Saints por 21-9. \u201cTacleamos bien en campo abierto. Los obligamos eventualmente a ser un ataque unidimensional, y cuando eres capaz de hacer eso, vas a ganar muchos juegos\u201d.<\/p>\n<p>John Harbaugh y el coordinador defensivo de los Ravens Wink Martindale podr\u00edan decir lo mismo. El encargado de la defensa de los Rams Brandon Staley podr\u00eda identificarse con eso. Al igual que su jefe, Sean McVay, un genio ofensivo cuya unidad se beneficia del caos que provoca su defensa.<\/p>\n<p>\u201cEste podr\u00eda ser el mejor triunfo del que haya sido parte\u201d, dijo Harbaugh, quien gan\u00f3 el Super Bowl en la temporada 2012 y ahora cuenta con ocho victorias fuera de casa en la postemporada, un r\u00e9cord de la NFL.<\/p>\n<p>No hubo muchos aficionados presentes en ninguno de los juegos debido a las restricciones relacionadas con la pandemia de COVID-19, y los estadios fueron privados de los c\u00e1nticos de \u201cDe-Fensa\u201d. Cuando se tiene una buena defensiva, es m\u00e1s f\u00e1cil transitar el camino al triunfo. Y posiblemente hacia el Super Bowl.<\/p>\n<p>A pesar de toda la complejidad que presume la NFL actualmente, en donde las ofensivas cuentan con m\u00e1s esquemas, formaciones y variables que nunca \u2014 sin mencionar la gran cantidad de reglas que favorecen las puntuaciones elevadas \u2014 la capacidad de presionar al quarterback ha demostrado ser el ant\u00eddoto perfecto. El All-Pro Aaron Donald es capaz de colapsar la parte interna de la l\u00ednea, en particular cuando cuenta con el complemento de un revitalizado Leonard Floyd y de cornerbacks estelares. Eso fue lo que present\u00f3 Los \u00c1ngeles en su triunfo sobre Seattle 30-20.<\/p>\n<p>Un grupo veterano plagado de dinamismo en todas las posiciones es la manera en que la unidad defensiva de Nueva Orle\u00e1ns est\u00e1 a la par de un ataque comandado por Drew Brees y Alvin Kamara. Esta bien podr\u00eda ser la mejor defensiva que hayan tenido los Saints desde que Brees lleg\u00f3 al equipo en 2006, y si esta es su \u00faltima temporada, sin duda cuenta con el complemento para que sea una despedida especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es momento de ver a Aaron Rodgers y sus Green Bay Packers en acci\u00f3n despu\u00e9s de una semana de descanso como el mejor equipo de la NFC, su rival son unos sorprendentes Rams que mostraron resiliencia y un gran car\u00e1cter para sobreponerse a la adversidad, como la lesi\u00f3n al inicio del partido de su Quarterback, John Wolford, ante los Seahawks.<\/p>\n","protected":false},"author":1,"featured_media":119494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,32],"tags":[],"class_list":["post-121716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rafaga-deportiva","category-portada"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/121716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=121716"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/121716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=121716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=121716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=121716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}