{"id":121814,"date":"2021-01-13T09:01:25","date_gmt":"2021-01-13T15:01:25","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=121814"},"modified":"2021-01-13T09:01:25","modified_gmt":"2021-01-13T15:01:25","slug":"asalta-manchester-united-liderato-de-premier-league","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/01\/13\/asalta-manchester-united-liderato-de-premier-league\/","title":{"rendered":"Asalta Manchester United liderato de Premier League"},"content":{"rendered":"<p><a href=\"https:\/\/apnews.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Agencias\/<\/a>\u00a0Ciudad de M\u00e9xico.- Han pasado varios a\u00f1os de turbulencia y desembolsos. Pero el Manchester United est\u00e1 de vuelta en un sitio que sol\u00eda conocer muy bien.<\/p>\n<p>La cima de la Liga Premier.<\/p>\n<p>Una victoria de 1-0 obtenida el martes ante el Burnley gracias a un tiro de volea de Paul Pogba coloc\u00f3 al United encima de Liverpool en el sitio de honor de la liga, tras 17 fechas y al cumplirse casi la primera mitad de la campa\u00f1a.<\/p>\n<p>\u201cEstamos exactamente en el lugar que nos corresponde\u201d, dijo el mediocampista del United, Nemanja Matic.<\/p>\n<p>El gran Alex Ferguson dirig\u00eda al United la \u00faltima vez que fue l\u00edder de la tabla a estas alturas de la campa\u00f1a. Fue en 2012-13, cuando Ferguson termin\u00f3 conquistando lo que ser\u00eda su \u00faltimo cetro como t\u00e9cnico de los Red Devils.<\/p>\n<p>\u00bfPuede hacer lo mismo Ole Gunnar Solskjaer?<\/p>\n<p>El estratega noruego dijo esta semana que \u201cnadie recuerda qu\u00e9 equipo era l\u00edder en enero\u201d. Sin embargo, se mostr\u00f3 satisfecho una vez que son\u00f3 el silbatazo final.<\/p>\n<p>Su alegr\u00eda es justificada, ante las cr\u00edticas que ha debido soportar durante sus dos a\u00f1os en el puesto, proncipalmente por parte de quienes creen que no est\u00e1 capacitado para ser t\u00e9cnico en este nivel.<\/p>\n<p>Por ahora, Solskjaer ha conseguido algo que se les neg\u00f3 a David Moyes, Louis van Gaal y Jos\u00e9 Mourinho, sus tres antecesores luego del retiro de Ferguson. El United tom\u00f3 una ventaja de tres puntos sobre el Liverpool, si bien esta podr\u00eda ser borrada pronto, pues los dirigidos por Solskjaer visitar\u00e1n Anfield el domingo.<\/p>\n<p>\u201cEstamos listos, emocionados y hambrientos de conseguir esto\u201d, dijo Solskjaer. \u201cSer\u00e1 otra prueba de car\u00e1cter y calidad. Estamos en una buena situaci\u00f3n para esto\u201d.<\/p>\n<p>El partido ante Burnley fue sopor\u00edfero, como suele ocurrir en Turf Moor. Los locales se defendieron con orden antes de quedar condenados por un golpe de mala fortuna a los 71 minutos.<\/p>\n<p>Poga lleg\u00f3 a la cita con un centro de Marcus Rashford. Conect\u00f3 de primera intenci\u00f3n desde los linderos del \u00e1rea y el bal\u00f3n se desvi\u00f3 en la pierna estirada de Matt Lowton, lateral derecho del Burnley, antes de pasar entre pas piernas del arquero Nick Pope.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=eYhZc0-XLOo<\/p>\n<h2>SHEFFIELD GANA AL FIN<\/h2>\n<p>El colista Sheffield United puso fin a la racha sin victorias m\u00e1s larga en el inicio de una temporada de la Liga Premier al vencer el martes 1-0 a Newcastle, cortes\u00eda del penal que Billy Sharp convirti\u00f3 a los 73 minutos.<\/p>\n<p>Los anfitriones finalmente cantaron victoria \u2014 en su 18vo partido de la campa\u00f1a \u2014 tras un despiste del capit\u00e1n de Newcastle Federico Fern\u00e1ndez. El central argentino manote\u00f3 el bal\u00f3n dentro del \u00e1rea.<\/p>\n<p>Sharp, quien hab\u00eda ingresado a los 59 minutos, hizo que el arquero rival Karl Darlow se tirase al otro lado para firmar apenas el noveno gol de su equipo en la temporada.<\/p>\n<p>Con Newcastle en inferioridad num\u00e9rica desde los 45 minutos por la expulsi\u00f3n del extremo Ryan Fraser, Sheffield United lo tuvo todo al alcance para la victoria.<\/p>\n<p>Nadie en la Premier, cuya temporada inaugural se remonta a 1992, hab\u00eda transitado las primeras 17 jornadas sin ganar. El \u00faltimo triunfo de Sheffield United en la liga se remonta a hace seis meses, imponi\u00e9ndose 3-0 ante Chelsea el 11 de julio. Ven\u00eda de ganarle al Bristol Rovers de la tercera divisi\u00f3n el s\u00e1bado por la Copa FA.<\/p>\n<p>Sheffield United acumula cinco puntos, con lo que el equipo Chris Wilder qued\u00f3 a nueve unidades de la salvaci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" title=\"Sheffield United 1-0 Newcastle United | Premier League Highlights | FIRST PL WIN OF THE SEASON. \ud83d\udca5\ud83d\udca5\ud83d\udca5\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/hoHbrYTA9yI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2>EVERTON SE COLOCA 4TO.<\/h2>\n<p>Michael Keane consigui\u00f3 el tanto que mantuvo en pie las aspiraciones de Liga de Campeones del Everton, que se impuso 2-1 en su visita al Wolverhampton.<\/p>\n<p>Un cabezazo del zaguero central a los 77 minutos entr\u00f3 pegado a segundo poste y coloc\u00f3 al Everton en el cuarto sitio, cuatro unidades detr\u00e1s del United.<\/p>\n<p>Una volea del portugu\u00e9s R\u00faben Neves a los 14 minutos igual\u00f3 el marcador por los Wolves, que hab\u00eda quedado en desventaja a los 6 por el primer tanto de Alex Iwob dentro de la liga en 17 meses.<\/p>\n<p>Wolverhampton ha ganado s\u00f3lo uno de ocho encuentros de la Premier desde finales de noviembre, cuando su delantero mexicano Ra\u00fal Jim\u00e9nez sufri\u00f3 una fractura craneal. Los Wolves est\u00e1n hundidos en el 14to sitio.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=6mvix4nuOAI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias al gol de Paul Pogba, que cay\u00f3 cuando solo restaban 20 minutos para el final del encuentro, Manchester United volvi\u00f3 a ganar por Premier League y mejor\u00f3 su lugar en la tabla de posiciones, sac\u00e1ndole tres puntos de ventaja a Liverpool de cara al cl\u00e1sico. Ciertamente, los locales impusieron resistencia, pero Bruno Fernandes y compa\u00f1\u00eda merecieron quedarse con la victoria, teniendo en cuenta lo hecho a lo largo de todo el partido. <\/p>\n","protected":false},"author":1,"featured_media":121302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[9,32],"tags":[],"class_list":["post-121814","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-rafaga-deportiva","category-portada","post_format-post-format-video"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/121814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=121814"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/121814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media\/121302"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=121814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=121814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=121814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}