{"id":122238,"date":"2021-01-18T09:36:48","date_gmt":"2021-01-18T15:36:48","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=122238"},"modified":"2021-01-18T09:36:48","modified_gmt":"2021-01-18T15:36:48","slug":"tenistas-en-cuarentena-tratan-de-entrenar-en-australia","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/01\/18\/tenistas-en-cuarentena-tratan-de-entrenar-en-australia\/","title":{"rendered":"Tenistas en cuarentena tratan de entrenar en Australia"},"content":{"rendered":"<p><a href=\"https:\/\/apnews.com\/\" rel=\"noopener noreferrer\" target=\"_blank\">Agencias<\/a>, Ciudad de M\u00e9xico.- Mientras las principales estrellas del tenis llegan a Melbourne para el pr\u00f3ximo Grand Slam, muchos australianos cuestionan la decisi\u00f3n de organizar el torneo mientras miles de ciudadanos est\u00e1n varados en el extranjero debido a la pandemia del coronavirus.<\/p>\n<p>Angelique Kerber, que gan\u00f3 el Abierto de Australia en 2016, pas\u00f3 su cumplea\u00f1os en cuarentena el lunes. Otros a\u00f1os atr\u00e1s, la alemana hab\u00eda pasado el d\u00eda jugando o prepar\u00e1ndose para partidos en las \u00faltimas rondas del torneo.<\/p>\n<p>Esta vez, dado que el Grand Slam que abre la temporada no empieza hasta el 8 de febrero debido a las restricciones a los viajes asociadas a la pandemia del COVID-19, tuvo que conformarse con un mensaje compartido en redes sociales por los organizadores del Abierto de Australia para celebrar la ocasi\u00f3n.<\/p>\n<p>Diego Schwartzman, semifinalista del \u00faltimo Abierto de Francia, busc\u00f3 salir de la monoton\u00eda a trav\u00e9s de una transmisi\u00f3n en vivo en Instagram que dur\u00f3 casi 24 minutos.<\/p>\n<p>\u201cNos estamos volviendo locos ac\u00e1\u201d, expres\u00f3 Schwartzman, con una pizca de bueno humor al tiempo que segu\u00eda incidencias del campeonato de f\u00fatbol en su natal Argentina.<\/p>\n<p>Acompa\u00f1ado por su novia Eugenia De Martino en la habitaci\u00f3n de su hotel, Schwartzman mostr\u00f3 su termo para beber yerba de mate y una bicicleta para ejercitarse.<\/p>\n<p>Kerber y Schwartzman est\u00e1n entre los 72 jugadores que cumplen un estricto confinamiento de 14 d\u00edas despu\u00e9s de que se detectaran cinco positivos en coronavirus en los pasajes de los vuelos arrendados que llevaron a casi 1.200 tenistas, entrenadores, autoridades y periodistas a Melbourne para un torneo que ten\u00eda fama de alegre, tanto as\u00ed que en el circuito se le conoce como el \u201cHappy Slam\u201d.<\/p>\n<p>Eso implica que los jugadores afectados no podr\u00e1n salir de sus habitaciones de hotel para entrenar durante 14 d\u00edas, creando un periodo de preparaci\u00f3n al torneo con dos velocidades. Los que cumplen un r\u00e9gimen de cuarentena menos riguroso podr\u00e1n entrenar cinco horas al d\u00eda.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Allez gute zum geburtstag <a href=\"https:\/\/twitter.com\/AngeliqueKerber?ref_src=twsrc%5Etfw\">@AngeliqueKerber<\/a>. <\/p>\n<p>Not your typical <a href=\"https:\/\/twitter.com\/hashtag\/AusOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#AusOpen<\/a> birthday. Hope you enjoy these memories. <a href=\"https:\/\/t.co\/Rk7QqSlMIc\">pic.twitter.com\/Rk7QqSlMIc<\/a><\/p>\n<p>&mdash; #AusOpen (@AustralianOpen) <a href=\"https:\/\/twitter.com\/AustralianOpen\/status\/1350998167026872327?ref_src=twsrc%5Etfw\">January 18, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Estas sesiones al aire libre comenzaron el lunes en Melbourne. Los jugadores de un grupo m\u00e1s peque\u00f1o de jugadores que aterriz\u00f3 en Adelaida, la capital de Australia del Sur, y que incluye a Serena Williams, Naomi Osaka, Novak Djokovic y Rafael Nadal, tambi\u00e9n pueden entrenar siguiendo con el protocolo de seguridad.<\/p>\n<p>Tenistas como Yulia Putintseva y Belinda Bencic se quejaron en un principio en medios sociales de haber sido mal informadas sobre las normas de cuarentena, pero han encontrado formas de entrenar en interior, como lanzar pelotas contra la pared y las ventanas o con otros m\u00e9todos curiosos de ejercitarse.<\/p>\n<p>Algunos tenistas se han expresado con enojo por quedar bajo la categor\u00eda de contacto cercano s\u00f3lo por haber estado a bordo del vuelo con personas que dieron positivo. Pero las autoridades sanitarias, el gobierno local y del tenis se\u00f1alaron que todos los jugadores sab\u00edan de antemano sobre los riesgos.<\/p>\n<p>\u201cHa habido un poco de ruido por parte de un grupo de jugadores sobre las reglas. Bueno, las reglas aplican a ellos como a todos los dem\u00e1s, y todos ellos fueron informados antes de venir y esa fue la condici\u00f3n con lo que viajaron\u201d, dijo el primer ministro del estado de Victoria, Daniel Andrews, el lunes. \u201cNo hay un tratamiento especial &#8230; como el virus no trata a nadie de manera especial, as\u00ed que nosotros tampoco lo vamos a hacer\u201d.<\/p>\n<p>En respuesta a versiones no confirmadas de que Djokovic, ocho veces campe\u00f3n del Abierto de Australia, propuso una serie de ideas para modificar las condiciones de cuarenta de los jugadores, Andrews sali\u00f3 al paso: \u201cLa gente tiene la libertad de presentar listas de demandas, pero la respuesta es no\u201d.<\/p>\n<p>\u00abSi quieres venir a Australia durante una pandemia, tienes que ser una estrella del deporte, una celebridad del cine o un magnate multimillonario de los medios\u00bb, dijo el usuario Daniel Bleakley en Twitter, utilizando el hashtag #strandedAussies (australianos varados). \u00abLa ciudadan\u00eda y un pasaporte australiano por s\u00ed solos no son suficientes\u00bb.<\/p>\n<p>Otros dijeron que los fondos utilizados para albergar el torneo podr\u00edan haberse desviado para aumentar las instalaciones de cuarentena de los hoteles y los sistemas de salud con el objetivo de ayudar a regresar a los australianos varados.<\/p>\n<p>Las tensiones ponen de relieve los desaf\u00edos que enfrenta el anfitri\u00f3n de los Juegos Ol\u00edmpicos, Jap\u00f3n, ya que la opini\u00f3n p\u00fablica se opone en gran medida al evento programado del 23 de julio al 8 de agosto en Tokio.<\/p>\n<p>Una encuesta de este mes detect\u00f3 que el 80% de los japoneses quieren que los juegos se cancelen o se retrasen a medida que crecen las preocupaciones sobre un aumento r\u00e9cord de casos de coronavirus en todo el pa\u00eds. Sin embargo, el primer ministro Yoshihide Suga prometi\u00f3 el lunes seguir adelante con los preparativos ol\u00edmpicos.<\/p>\n<p>Funcionarios en el estado de Victoria de Australia, sede del Abierto, dijeron que la organizaci\u00f3n del torneo no perjudic\u00f3 a unos 40,000 australianos varados.<\/p>\n<p>\u00abNadie ha sido excluido de otras jurisdicciones en Victoria en virtud de que el Abierto de Australia sigue adelante\u00bb, dijo Brett Sutton, director m\u00e9dico de Victoria. \u00abSon decisiones separadas que se toman por sus propios m\u00e9ritos\u00bb.<\/p>\n<p>Las fronteras internacionales de Australia est\u00e1n pr\u00e1cticamente cerradas, aunque se hacen excepciones en circunstancias especiales. Todos los reci\u00e9n llegados deben hacer una cuarentena obligatoria. Cada estado de Australia tiene sus propias restricciones fronterizas y de desplazamientos, que pueden cambiar con rapidez.<\/p>\n<p>El estado de Victoria, que tiene Melbourne como su capital, registr\u00f3 810 de las 909 muertes por COVID-19 en Australia, la mayor\u00eda durante una segunda oleada de contagios hace tres meses que supuso toques de queda y cuarentenas para la ciudad.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud835\ude88\ud835\ude98\ud835\ude9e&#39;\ud835\ude9f\ud835\ude8e \ud835\ude76\ud835\ude98\ud835\ude9d \ud835\ude7c\ud835\ude8a\ud835\ude92\ud835\ude95 \ud83d\udce9<a href=\"https:\/\/twitter.com\/hashtag\/AusOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#AusOpen<\/a> \ud83d\udd1c <a href=\"https:\/\/twitter.com\/hashtag\/AO2021?src=hash&amp;ref_src=twsrc%5Etfw\">#AO2021<\/a> <a href=\"https:\/\/t.co\/k15CHXUTDU\">pic.twitter.com\/k15CHXUTDU<\/a><\/p>\n<p>&mdash; #AusOpen (@AustralianOpen) <a href=\"https:\/\/twitter.com\/AustralianOpen\/status\/1351041907359690752?ref_src=twsrc%5Etfw\">January 18, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Australia ha reducido a la mitad el n\u00famero de personas que pueden regresar al pa\u00eds cada semana a medida que aumentan los casos positivos de coronavirus en cuarentena en hoteles, lo que llev\u00f3 a la aerol\u00ednea Emirates a suspender indefinidamente los vuelos a S\u00eddney, Melbourne y Brisbane.<\/p>\n","protected":false},"author":1,"featured_media":117235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-122238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rafaga-deportiva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/122238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=122238"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/122238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=122238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=122238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=122238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}