{"id":129887,"date":"2021-04-15T22:20:18","date_gmt":"2021-04-16T03:20:18","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=129887"},"modified":"2021-04-15T22:20:18","modified_gmt":"2021-04-16T03:20:18","slug":"deja-lamarcus-aldridge-la-duela-por-arritmia-en-nba","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/04\/15\/deja-lamarcus-aldridge-la-duela-por-arritmia-en-nba\/","title":{"rendered":"Deja LaMarcus Aldridge la duela por arritmia en NBA"},"content":{"rendered":"<p><a href=\"https:\/\/apnews.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Agencias<\/a>, Ciudad de M\u00e9xico.- LaMarcus Aldridge anunci\u00f3 su retiro de la NBA tras revelar que padeci\u00f3 arritmia durante su \u00faltimo partido con los Nets de Brooklyn.<\/p>\n<p>El ala-p\u00edvot de 35 a\u00f1os public\u00f3 una declaraci\u00f3n en sus redes sociales, se\u00f1alando que el problema cardiaco que sufri\u00f3 durante y despu\u00e9s de la derrota de Brooklyn ante los Lakers de Los \u00c1ngeles el s\u00e1bado pasado fue \u201cuna de las cosas que m\u00e1s me han asustado en mi vida\u201d.<\/p>\n<p>Aldridge, quien fue diagnosticado sindrome de Wolff-Parkinson-White \u2014 una afecci\u00f3n que puede acelerar el ritmo cardiaco \u2014 como novato en 2007, dijo que se siente mejor ahora tras haber sido examinado por los m\u00e9dicos, pero que tom\u00f3 la decisi\u00f3n de poner fin a su carrera profesional de 15 temporadas.<\/p>\n<p>\u201cDurante 15 a\u00f1os he puesto el b\u00e1squetbol por delante y, ahora, lleg\u00f3 el momento de poner por delante mi salud y mi familia\u201d.<\/p>\n<p>El siete veces All-Star hab\u00eda firmado con los Nets el 28 de marzo y se hab\u00eda consolidado como el centro titular del equipo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Tough day for me but I appreciate all the love&#8230;.. on social media and people who reached out personally. \ud83d\ude4f\ud83c\udffe<\/p>\n<p>&mdash; LaMarcus Aldridge (@aldridge_12) <a href=\"https:\/\/twitter.com\/aldridge_12\/status\/1382826844215332867?ref_src=twsrc%5Etfw\">April 15, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Se perdi\u00f3 los \u00faltimos dos partidos por lo que los Nets describieron como un quebranto de salud no relacionado al COVID-19.<\/p>\n<p>El gerente general de los Nets Sean Marks dijo que el equipo respald\u00f3 sin traba alguna la decisi\u00f3n de Aldridge.<\/p>\n<p>\u201cSabemos que esta no fue una decisi\u00f3n f\u00e1cil para \u00e9l, pero despu\u00e9s de un cuidados proceso de charlas y consultas con m\u00faltiples expertos m\u00e9dicos, \u00e9l tom\u00f3 la mejor decisi\u00f3n para \u00e9l, su familia y para su vida tras el baloncesto\u201d, dijo Marks.<\/p>\n<p>Aldridge firm\u00f3 con los Nets tras acordar la rescisi\u00f3n de su contrato con los Spurs de San Antonio y de inmediato aport\u00f3 una importante presencia bajo el aro, una de los pocas cosas que le falta a un equipo repleto de estrellas.<\/p>\n<p>El mejor de los cinco partidos de Aldridge con los Nets fue el anterior al sentirse mal \u2014 anot\u00f3 22 puntos en una victoria sobre Nueva Orleans el 7 de abril.<\/p>\n<p>La segunda selecci\u00f3n del draft de 2006 siempre estuvo entre los mejores de su posici\u00f3n, promediando 19,4 puntos en una carrera que comenz\u00f3 con nueva temporadas en Portland. Milit\u00f3 con los Spurs durante cinco campa\u00f1as y medio, y en cinco ocasiones fue seleccionado para el equipo ideal de la NBA.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"zxx\" dir=\"ltr\"><a href=\"https:\/\/t.co\/q69S0VhdFf\">pic.twitter.com\/q69S0VhdFf<\/a><\/p>\n<p>&mdash; LaMarcus Aldridge (@aldridge_12) <a href=\"https:\/\/twitter.com\/aldridge_12\/status\/1382706719684444161?ref_src=twsrc%5Etfw\">April 15, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aldridge eligi\u00f3 a los Nets despu\u00e9s de acordar un buyout con los San Antonio Spurs, donde pas\u00f3 las cinco temporadas y media anteriores. Pas\u00f3 los primeros nueve a\u00f1os de su carrera con los Portland Trail Blazers. Aldridge promedi\u00f3 12.8 puntos en cinco juegos con los Nets. Fue escogido segundo en el draft de la NBA de 2006 y tuvo promedios de 19.4 puntos y 8.2 rebotes en su carrera, seleccionado siete veces al Juego de Estrellas.<\/p>\n","protected":false},"author":5,"featured_media":129891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,32],"tags":[],"class_list":["post-129887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rafaga-deportiva","category-portada"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/129887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=129887"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/129887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media\/129891"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=129887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=129887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=129887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}