{"id":131496,"date":"2021-05-08T10:53:49","date_gmt":"2021-05-08T15:53:49","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=131496"},"modified":"2021-05-08T10:53:49","modified_gmt":"2021-05-08T15:53:49","slug":"niega-panama-aval-para-juzgar-a-ex-gobernador-roberto-borge-por-delincuencia-organizada-en-mexico","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/05\/08\/niega-panama-aval-para-juzgar-a-ex-gobernador-roberto-borge-por-delincuencia-organizada-en-mexico\/","title":{"rendered":"Niega Panam\u00e1 aval para juzgar a ex Gobernador Roberto Borge por delincuencia organizada en M\u00e9xico"},"content":{"rendered":"<p>Redacci\u00f3n InsurgentePress\/Ciudad de M\u00e9xico.- El Gobierno de Panam\u00e1 neg\u00f3 el aval a las autoridades mexicanas para juzgar a Roberto Borge ex mandatario priista de Quintana Roo por un quinto delito adicional ligado a delincuencia organizada que trae consigo la prisi\u00f3n preventiva de oficio en el Pa\u00eds.<\/p>\n<p>La Direcci\u00f3n de Asuntos Jur\u00eddicos Internacionales y Tratados del Ministerio de Relaciones Exteriores de la Rep\u00fablica de Panam\u00e1 comunic\u00f3 a la Embajada de M\u00e9xico que la solicitud no reun\u00eda los elementos para proseguir con el an\u00e1lisis requerido en la materia, establecidos en el art\u00edculo XVII del Tratado de Extradici\u00f3n signado entre ambos pa\u00edses en 2004.<\/p>\n<p>De continuar con el inter\u00e9s de ampliaci\u00f3n y consentimiento para el levantamiento a la regla de especialidad en el caso de Borge Angulo, deber\u00e1 remitir la documentaci\u00f3n para cumplir todos los requisitos dispuestos en el Tratado.<\/p>\n<p>Lo anterior, indic\u00f3 el Gobierno de Panam\u00e1, permitir\u00e1 evaluar y basado en eso se conocer\u00e1 el estado que guarda la petici\u00f3n hecha por M\u00e9xico sobre la ampliaci\u00f3n a la extradici\u00f3n, por un quinto delito, consistente en delincuencia organizada y consentimiento para el levantamiento a la regla de especialidad de acuerdo a la reuni\u00f3n virtual programada el 15 de marzo.<\/p>\n<p>\u00abEl principio de especialidad es un elemento del Derecho Internacional, aplicable a los procesos de extradici\u00f3n y consiste en que el Estado requiriente s\u00f3lo puede juzgar a una persona extraditada por las ofensas por las cuales su extradici\u00f3n fue autorizada por el Estado requerido.<\/p>\n<p>Es decir, M\u00e9xico s\u00f3lo podr\u00eda enjuiciar a Borge Angulo, detenido en Panam\u00e1 el cinco de junio de 2017, por los cuatro delitos que formaron parte de la solicitud de extradici\u00f3n aprobada el 15 de septiembre de ese mismo a\u00f1o.<\/p>\n<p>El 4 de enero de 2018, el Gobierno de Panam\u00e1 extradit\u00f3 a Borge Angulo por los delitos de Operaciones con recursos de procedencia il\u00edcita o lavado de dinero (381\/ 2017); peculado (159\/ 2017), aprovechamiento il\u00edcito del poder y desempe\u00f1o irregular de la funci\u00f3n p\u00fablica (151\/ 2017); y ejercicio indebido de la funci\u00f3n p\u00fablica (154\/ 2017)<\/p>\n<p>El Gobierno de Panam\u00e1 a trav\u00e9s del Ministerio de Relaciones Exteriores comunic\u00f3 a su hom\u00f3logo de M\u00e9xico la negativa sobre el aval al quinto delito contra de Borge Angulo mediante una nota diplom\u00e1tica con fecha de 15 de marzo.<\/p>\n<p>Se\u00f1al\u00f3 que se incumple con el requisito de acompa\u00f1ar su solicitud con documentos como la orden de aprehensi\u00f3n por el nuevo il\u00edcito de delincuencia organizada.<\/p>\n<p>El 8 de mayo de 2020, la Secretar\u00eda de Relaciones Exteriores (SRE) solicit\u00f3 el consentimiento de Panam\u00e1 para procesar a Borge Angulo por el delito de delincuencia organizada con la finalidad de cometer operaciones con recursos de procedencia il\u00edcita en M\u00e9xico.<\/p>\n<p>El pasado 26 de febrero, la SRE envi\u00f3 un recordatorio a las autoridades paname\u00f1as para conocer el estado actual de su solicitud debido a que durante la pandemia el tr\u00e1mite hab\u00eda sido suspendido. A esta \u00faltima vino la respuesta negativa.<\/p>\n<p>El pasado 29 de enero, el Juzgado Primero de Distrito neg\u00f3 un recurso de amparo 252\/2020 al ex Gobernador Borge Angulo y notific\u00f3 el dictamen a la Fiscal\u00eda Especializada en Combate a la Corrupci\u00f3n de Quintana Roo.<\/p>\n<p>El Juez determin\u00f3 que existen elementos suficientes para seguir el proceso de la carpeta administrativa 154\/2017 contra Borge Angulo como presunto responsable del delito de desempe\u00f1o irregular de la funci\u00f3n p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n InsurgentePress\/Ciudad de M\u00e9xico.- El Gobierno de Panam\u00e1 neg\u00f3 el aval a las autoridades mexicanas para juzgar a Roberto Borge ex mandatario priista de Quintana Roo por un quinto delito adicional ligado a delincuencia organizada que trae consigo la prisi\u00f3n preventiva de oficio en el Pa\u00eds. La Direcci\u00f3n de Asuntos Jur\u00eddicos Internacionales y Tratados del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":131498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,32],"tags":[],"class_list":["post-131496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados","category-portada"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/131496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=131496"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/131496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=131496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=131496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=131496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}