{"id":132169,"date":"2021-05-17T12:33:49","date_gmt":"2021-05-17T17:33:49","guid":{"rendered":"https:\/\/insurgentepress.com.mx\/?p=132169"},"modified":"2021-05-17T12:33:49","modified_gmt":"2021-05-17T17:33:49","slug":"hereda-newman-coleccion-de-tarjetas-valuadas-en-20-millone-de-dolares-en-eeuu","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2021\/05\/17\/hereda-newman-coleccion-de-tarjetas-valuadas-en-20-millone-de-dolares-en-eeuu\/","title":{"rendered":"Hereda Newman colecci\u00f3n de tarjetas valuadas en 20 millone de d\u00f3lares en EEUU"},"content":{"rendered":"<p>Agencias\/Ciudad de M\u00e9xico.- Cuando el m\u00e9dico de Florida Thomas Newman muri\u00f3 de Covid-19, dej\u00f3 a su familia un gran legado: una colecci\u00f3n de tarjetas deportivas por un valor cercano a los 20 millones de d\u00f3lares, que incluye una de Babe Ruth que podr\u00eda alcanzar un nuevo r\u00e9cord mundial.<\/p>\n<p>Fue amor, no dinero, lo que impuls\u00f3 a Newman a comenzar su colecci\u00f3n hace unos 40 a\u00f1os, viajando por Estados Unidos para conseguirlas en convenciones y guardando sus tarjetas en una caja fuerte en su casa de Tampa.<\/p>\n<p>\u00abAmaba a sus beb\u00e9s de papel\u00bb, dijo su viuda Nancy Newman. \u00abLe dieron tanta alegr\u00eda\u00bb.<\/p>\n<p>Newman, quien muri\u00f3 en enero a los 73 a\u00f1os, mantuvo su colecci\u00f3n de m\u00e1s de 1,000 tarjetas coleccionables antiguas y modernas de b\u00e9isbol, f\u00fatbol y hockey lejos de su familia y amigos cercanos.<\/p>\n<p>Ahora se compartir\u00e1 con el mundo en una subasta online en Memory Lane, con sede en California, entre el 21 de junio y el 10 de julio.<\/p>\n<p>\u00abEs genial para su legado que haya dedicado 40 a\u00f1os al coleccionismo y que ahora est\u00e9 recibiendo el reconocimiento que probablemente estaba postergado\u00bb, dijo su hijo Stewart Newman.<\/p>\n<p>La joya de la corona es una tarjeta de Babe Ruth de 1933 que los subastadores creen que podr\u00eda romper el r\u00e9cord mundial de 5,2 millones de d\u00f3lares establecido en enero para cualquier tarjeta deportiva.<\/p>\n<p>Es la \u00fanica tarjeta de Babe Ruth de este tipo con condici\u00f3n Mint 9 que se conozca y se subastar\u00e1 en un momento en que los precios de las tarjetas comerciales deportivas se han disparado. El estado de las cartas se clasifica en una escala de 1 a 10, as\u00ed que 9 es casi perfecto.<\/p>\n<p>Newman adquiri\u00f3 la tarjeta Babe Ruth hace unos 15-20 a\u00f1os de un comerciante a una fracci\u00f3n de su valor actual y a lo largo de los a\u00f1os rechaz\u00f3 cientos de ofertas para venderla, dijo su hijo.<\/p>\n<p>Otros \u00edtems destacados son una tarjeta de novato de Babe Ruth Sporting News de Babe Ruth de 1916 y una casi perfecta tarjeta de novato de Mickey Mantle de 1952, que se espera que se venda por alrededor de 1 mill\u00f3n de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el m\u00e9dico de Florida Thomas Newman muri\u00f3 de COVID-19, dej\u00f3 a su familia un gran legado: una colecci\u00f3n de tarjetas deportivas por un valor cercano a los 20 millones de d\u00f3lares, que incluye una de Babe Ruth que podr\u00eda alcanzar un nuevo r\u00e9cord mundial. Fue amor, no dinero, lo que impuls\u00f3 a Newman a comenzar su colecci\u00f3n hace unos 40 a\u00f1os, viajando por Estados Unidos para conseguirlas en convenciones y guardando sus tarjetas en una caja fuerte en su casa de Tampa.<\/p>\n","protected":false},"author":3,"featured_media":124605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,32],"tags":[],"class_list":["post-132169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-startup","category-portada"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/132169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=132169"}],"version-history":[{"count":0,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/132169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=132169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=132169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=132169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}