{"id":136682,"date":"2024-07-14T11:09:44","date_gmt":"2024-07-14T16:09:44","guid":{"rendered":"https:\/\/insurgentepress.mx\/?p=136682"},"modified":"2024-07-09T19:11:47","modified_gmt":"2024-07-10T00:11:47","slug":"arrestan-en-alemania-a-tercer-sospechoso-de-intento-de-extorsion-a-la-familia-schumacher","status":"publish","type":"post","link":"https:\/\/insurgentepress.mx\/index.php\/2024\/07\/14\/arrestan-en-alemania-a-tercer-sospechoso-de-intento-de-extorsion-a-la-familia-schumacher\/","title":{"rendered":"Arrestan en Alemania a tercer sospechoso de intento de extorsi\u00f3n a la familia Schumacher"},"content":{"rendered":"<p>Agencias, Ciudad de M\u00e9xico.-\u00a0Investigadores alemanes indicaron el viernes que arrestaron a un tercer sospechoso de intento de extorsi\u00f3n a la familia del expiloto de F\u00f3rmula Uno Michael Schumacher.<\/p>\n<p>Un sujeto de 52 a\u00f1os, que fue detenido el jueves cerca de la ciudad de Wuppertal al oeste de Alemania, trabaj\u00f3 como agente de seguridad de la familia, confirm\u00f3 la agencia de noticias alemana dpa, citando a la fiscal\u00eda.<\/p>\n<p>Los investigadores registraron su casa y se llevaron algunas pertenencias como tel\u00e9fonos m\u00f3viles, discos duros, memorias USB para encontrar evidencia, indic\u00f3 el fiscal Wolf-Tilman Baumert. El nombre del sospechoso no fue hecho p\u00fablico acorde con las leyes de privacidad de Alemania.<\/p>\n<p>La fiscal\u00eda del caso arresto el mes pasado a otros dos hombres y dijo que la pareja \u2014de un padre e hijo de Wuppertal\u2014 le dijo a los empleados de la familia que estaban en posesi\u00f3n de archivos que la familia no quer\u00edan que fueran publicados.<\/p>\n<p>Presuntamente los dos hombres demandaron un pago de varios millones de euros o publicar\u00edan los archivos en la Dark Web, a\u00f1adi\u00f3 la fiscal\u00eda. Como prueba, la familia envi\u00f3 parte de los archivos a la familia.<\/p>\n<p>Baumert indic\u00f3 que uno de los primeros detenidos le coment\u00f3 a los investigadores que el sujeto de 52 a\u00f1os les entreg\u00f3 los archivos para la extorsi\u00f3n. Baumert indic\u00f3 que este hombre hab\u00eda trabajado con la familia Schumacher y \u201ctuvo la tarea de digitalizar fotos privadas\u201d.<\/p>\n<p>De ser sentenciados, los sospechosos podr\u00edan recibir un castigo de una multa o prisi\u00f3n de hasta cinco a\u00f1os, indic\u00f3 a fiscal\u00eda.<\/p>\n<p>Schumacher sufri\u00f3 una lesi\u00f3n cerebral casi fatal mientras esquiaba en los Alpes Franceses en Meribel en diciembre del 2013. Se cay\u00f3 y se peg\u00f3 en la cabeza con una roca que parti\u00f3 su casco a la mitad. Desde que sali\u00f3 del hospital en septiembre 2014, el siete veces campe\u00f3n de la F1 ha recibido atenci\u00f3n privada en la casa de la familia en Suiza.<\/p>\n<p>Schumacher, de 55 a\u00f1os, se retir\u00f3 de la F1 en el 2012 tras ganar 91 carrera y cinco t\u00edtulos consecutivos con Ferrari entre el 2000 y 2004. Adem\u00e1s el alem\u00e1n gan\u00f3 dos campeonatos con Benetton en 1994 y 1995.<\/p>\n<p>En mayo la familia Schumacher gan\u00f3 una acci\u00f3n legal contra una revista de celebridades que public\u00f3 una entrevista ficticia con el piloto de F1 generada con inteligencia artificial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agencias, Ciudad de M\u00e9xico.-\u00a0Investigadores alemanes indicaron el viernes que arrestaron a un tercer sospechoso de intento de extorsi\u00f3n a la familia del expiloto de F\u00f3rmula Uno Michael Schumacher. Un sujeto de 52 a\u00f1os, que fue detenido el jueves cerca de la ciudad de Wuppertal al oeste de Alemania, trabaj\u00f3 como agente de seguridad de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":136684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-136682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rafaga-deportiva"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/136682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/comments?post=136682"}],"version-history":[{"count":1,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/136682\/revisions"}],"predecessor-version":[{"id":136685,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/posts\/136682\/revisions\/136685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media\/136684"}],"wp:attachment":[{"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/media?parent=136682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/categories?post=136682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurgentepress.mx\/index.php\/wp-json\/wp\/v2\/tags?post=136682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}